{"id":22427,"date":"2026-05-13T06:56:54","date_gmt":"2026-05-13T10:56:54","guid":{"rendered":"https:\/\/nazarenonews.com.br\/?p=22427"},"modified":"2026-05-13T06:56:54","modified_gmt":"2026-05-13T10:56:54","slug":"dolar-encerra-ultimo-pregao-em-alta-de-009-aos-r-489","status":"publish","type":"post","link":"https:\/\/nazarenonews.com.br\/index.php\/2026\/05\/13\/dolar-encerra-ultimo-pregao-em-alta-de-009-aos-r-489\/","title":{"rendered":"D\u00f3lar encerra \u00faltimo preg\u00e3o em alta de 0,09%, aos R$ 4,89"},"content":{"rendered":"\n<p><strong><br>O d\u00f3lar fechou o \u00faltimo preg\u00e3o em leve alta de 0,09%, cotado a R$ 4,89.<\/strong><\/p>\n\n\n\n<p>O resultado foi registrado em meio ao avan\u00e7o dos contratos futuros de petr\u00f3leo e a divulga\u00e7\u00e3o dos \u00edndices de infla\u00e7\u00e3o no Brasil e nos Estados Unidos.<\/p>\n\n\n\n<p><strong>Para analistas do mercado financeiro, o quadro est\u00e1 associado \u00e0 abertura da curva de juros do pa\u00eds norte-americano, como consequ\u00eancia da alta do petr\u00f3leo e do \u00edndice de infla\u00e7\u00e3o dos Estados Unidos.&nbsp;<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cota\u00e7\u00e3o do euro<\/h2>\n\n\n\n<p><strong>O euro, por sua vez, encerrou o preg\u00e3o cotado em torno de R$ 5,76.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cota\u00e7\u00f5es<\/h2>\n\n\n\n<p>A tabela abaixo mostra as cota\u00e7\u00f5es cruzadas entre as principais moedas internacionais e o real. Cada c\u00e9lula indica quanto vale 1 unidade da moeda da linha em rela\u00e7\u00e3o \u00e0 moeda da coluna.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><thead><tr><th>C\u00d3DIGO<\/th><th>\ud83c\udde7\ud83c\uddf7 BRL<\/th><th>\ud83c\uddfa\ud83c\uddf8 USD<\/th><th>\ud83c\uddea\ud83c\uddfa EUR<\/th><th>\ud83c\uddec\ud83c\udde7 GBP<\/th><th>\ud83c\uddef\ud83c\uddf5 JPY<\/th><th>\ud83c\udde8\ud83c\udded CHF<\/th><th>\ud83c\udde8\ud83c\udde6 CAD<\/th><th>\ud83c\udde6\ud83c\uddfa AUD<\/th><\/tr><\/thead><tbody><tr><td><strong>BRL<\/strong><\/td><td>1<\/td><td>0,2045<\/td><td>0,1734<\/td><td>0,1504<\/td><td>32,2462<\/td><td>0,1597<\/td><td>0,2802<\/td><td>0,2813<\/td><\/tr><tr><td><strong>USD<\/strong><\/td><td>4,8891<\/td><td>1<\/td><td>0,8519<\/td><td>0,7387<\/td><td>157,65<\/td><td>0,7806<\/td><td>1,3698<\/td><td>1,3815<\/td><\/tr><tr><td><strong>EUR<\/strong><\/td><td>5,7670<\/td><td>1,1739<\/td><td>1<\/td><td>0,8672<\/td><td>185,07<\/td><td>0,9164<\/td><td>1,6080<\/td><td>1,6218<\/td><\/tr><tr><td><strong>GBP<\/strong><\/td><td>6,6241<\/td><td>1,3538<\/td><td>1,1531<\/td><td>1<\/td><td>213,41<\/td><td>1,0567<\/td><td>1,8542<\/td><td>1,8702<\/td><\/tr><tr><td><strong>JPY<\/strong><\/td><td>3,10104<\/td><td>0,634297<\/td><td>0,54032<\/td><td>0,468571<\/td><td>1<\/td><td>0,4951<\/td><td>0,86886<\/td><td>0,87627<\/td><\/tr><tr><td><strong>CHF<\/strong><\/td><td>6,2633<\/td><td>1,2811<\/td><td>1,0912<\/td><td>0,9463<\/td><td>201,97<\/td><td>1<\/td><td>1,7549<\/td><td>1,7699<\/td><\/tr><tr><td><strong>CAD<\/strong><\/td><td>3,5689<\/td><td>0,7300<\/td><td>0,6218<\/td><td>0,5393<\/td><td>115,10<\/td><td>0,5699<\/td><td>1<\/td><td>1,0085<\/td><\/tr><tr><td><strong>AUD<\/strong><\/td><td>3,5560<\/td><td>0,7239<\/td><td>0,6166<\/td><td>0,5347<\/td><td>114,12<\/td><td>0,5650<\/td><td>0,9915<\/td><td>1<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>Os dados s\u00e3o da&nbsp;<a href=\"https:\/\/br.investing.com\/currencies\/exchange-rates-table\" target=\"_blank\" rel=\"noreferrer noopener\">Investing.com<\/a>. &nbsp;&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O d\u00f3lar fechou o \u00faltimo preg\u00e3o em leve alta de 0,09%, cotado a R$ 4,89. O resultado foi registrado em meio ao avan\u00e7o dos contratos futuros de petr\u00f3leo e a divulga\u00e7\u00e3o dos \u00edndices de infla\u00e7\u00e3o no Brasil e nos Estados Unidos. Para analistas do mercado financeiro, o quadro est\u00e1 associado \u00e0 abertura da curva de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":21876,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[54],"tags":[],"_links":{"self":[{"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/22427"}],"collection":[{"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=22427"}],"version-history":[{"count":1,"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/22427\/revisions"}],"predecessor-version":[{"id":22428,"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/22427\/revisions\/22428"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/media\/21876"}],"wp:attachment":[{"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=22427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=22427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=22427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}