{"id":1904,"date":"2024-08-01T18:20:02","date_gmt":"2024-08-01T22:20:02","guid":{"rendered":"https:\/\/nazarenonews.com.br\/?p=1904"},"modified":"2024-08-01T18:20:02","modified_gmt":"2024-08-01T22:20:02","slug":"cliente-denuncia-loja-apos-encontrar-anzol-e-linha-de-pesca-em-lanche-de-fast-food-em-mt","status":"publish","type":"post","link":"https:\/\/nazarenonews.com.br\/index.php\/2024\/08\/01\/cliente-denuncia-loja-apos-encontrar-anzol-e-linha-de-pesca-em-lanche-de-fast-food-em-mt\/","title":{"rendered":"Cliente denuncia loja ap\u00f3s encontrar anzol e linha de pesca em lanche de fast food em MT"},"content":{"rendered":"\n<p>G1-MT<\/p>\n\n\n\n<p>Um cliente registrou um boletim de ocorr\u00eancia alegando que&nbsp;encontrou um anzol e uma linha de pesca dentro de um lanche que comprou em uma rede de fast food, em&nbsp;<a class=\"\" href=\"https:\/\/g1.globo.com\/mt\/mato-grosso\/cidade\/sorriso\/\">Sorriso<\/a>, a 420 km de Cuiab\u00e1, nessa ter\u00e7a-feira (30).<\/p>\n\n\n\n<p>O homem relatou \u00e0 pol\u00edcia que levou um susto ao notar os objetos. Conforme o relato, ele n\u00e3o chegou a ingerir o produto. Ainda de acordo com ele, a&nbsp;experi\u00eancia foi traum\u00e1tica.<\/p>\n\n\n\n<p>O\u00a0<a class=\"\" href=\"https:\/\/g1.globo.com\/mt\/mato-grosso\/\"><strong>g1\u00a0<\/strong><\/a>procurou o propriet\u00e1rio da lanchonete, que informou que\u00a0n\u00e3o existe nada relacionado a artigos de pesca dentro do estabelecimento, por isso, segundo ele, seria &#8220;praticamente imposs\u00edvel que algo assim aconte\u00e7a&#8221;.<\/p>\n\n\n\n<p>Ele explicou que os produtos utilizados na produ\u00e7\u00e3o dos lanches s\u00e3o comprados diretamente da franqueadora e que j\u00e1 chegam pr\u00e9-prontos. O propriet\u00e1rio ainda destacou que a prepara\u00e7\u00e3o do sandu\u00edche \u00e9 feita na frente dos clientes.<\/p>\n\n\n\n<p>Segundo a Pol\u00edcia Civil, o estabelecimento foi comunicado sobre o caso e<strong>&nbsp;o cliente teve o valor pago pelo lanche ressarcido<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>G1-MT Um cliente registrou um boletim de ocorr\u00eancia alegando que&nbsp;encontrou um anzol e uma linha de pesca dentro de um lanche que comprou em uma rede de fast food, em&nbsp;Sorriso, a 420 km de Cuiab\u00e1, nessa ter\u00e7a-feira (30). O homem relatou \u00e0 pol\u00edcia que levou um susto ao notar os objetos. Conforme o relato, ele [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1905,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1904"}],"collection":[{"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1904"}],"version-history":[{"count":1,"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1904\/revisions"}],"predecessor-version":[{"id":1906,"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1904\/revisions\/1906"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/media\/1905"}],"wp:attachment":[{"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}