{"id":10204,"date":"2025-03-18T08:00:35","date_gmt":"2025-03-18T12:00:35","guid":{"rendered":"https:\/\/nazarenonews.com.br\/?p=10204"},"modified":"2025-03-18T11:39:40","modified_gmt":"2025-03-18T15:39:40","slug":"celular-de-zampieri-gera-nova-fase-de-operacao-da-pf-por-esquema-de-sentencas-no-stj","status":"publish","type":"post","link":"https:\/\/nazarenonews.com.br\/index.php\/2025\/03\/18\/celular-de-zampieri-gera-nova-fase-de-operacao-da-pf-por-esquema-de-sentencas-no-stj\/","title":{"rendered":"Celular de Zampieri gera nova fase de opera\u00e7\u00e3o da PF por esquema de senten\u00e7as no STJ"},"content":{"rendered":"\n<p>A Pol\u00edcia Federal deflagrou, nesta ter\u00e7a-feira (18), nova fase da Opera\u00e7\u00e3o Sisamnes com o objetivo de investigar crimes de obstru\u00e7\u00e3o de Justi\u00e7a, viola\u00e7\u00e3o do sigilo funcional e corrup\u00e7\u00e3o ativa e passiva.&nbsp; A a\u00e7\u00e3o \u00e9 um desdobramento das investiga\u00e7\u00f5es a partir de informa\u00e7\u00f5es constatadas pelo celular do advogado Roberto Zampieri, ssassinado em Cuiab\u00e1 em 2023.<\/p>\n\n\n\n<p>Segundo as investiga\u00e7\u00f5es, foi identificada uma rede clandestina de monitoramento, com\u00e9rcio e repasse de informa\u00e7\u00f5es sigilosas sobre o andamento de investiga\u00e7\u00f5es sens\u00edveis supervisionadas pelo Superior Tribunal de Justi\u00e7a, frustrando, assim, a efetividade das deflagra\u00e7\u00f5es das opera\u00e7\u00f5es policiais.<\/p>\n\n\n\n<p>Assim, por determina\u00e7\u00e3o do Supremo Tribunal Federal, policiais federais cumprem um mandado de pris\u00e3o preventiva e quatro mandados de busca e apreens\u00e3o, no Tocantins, al\u00e9m das medidas de afastamento das fun\u00e7\u00f5es p\u00fablicas, proibi\u00e7\u00e3o de contato e sa\u00edda do pa\u00eds, e recolhimento de passaportes.<\/p>\n\n\n\n<p>A Pol\u00edcia Federal apura equema de corrup\u00e7\u00e3o e vazamento de informa\u00e7\u00f5es em 14 processos.&nbsp;Os crimes cometidos seriam de corrup\u00e7\u00e3o passiva e ativa, explora\u00e7\u00e3o de prest\u00edgio e viola\u00e7\u00e3o de sigilo funcional. Em alguns processos, h\u00e1 suspeita de mais de um crime.<\/p>\n\n\n\n<p>Investiga\u00e7\u00f5es baseadas na an\u00e1lise do celular de Zampieri levaram ao afastamento de dois desembargadores do TJMT e de cinco magistrados do Tribunal de Justi\u00e7a de Mato Grosso do Sul (TJMS).<\/p>\n\n\n\n<p>Rep\u00f3rter MT<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Federal deflagrou, nesta ter\u00e7a-feira (18), nova fase da Opera\u00e7\u00e3o Sisamnes com o objetivo de investigar crimes de obstru\u00e7\u00e3o de Justi\u00e7a, viola\u00e7\u00e3o do sigilo funcional e corrup\u00e7\u00e3o ativa e passiva.&nbsp; A a\u00e7\u00e3o \u00e9 um desdobramento das investiga\u00e7\u00f5es a partir de informa\u00e7\u00f5es constatadas pelo celular do advogado Roberto Zampieri, ssassinado em Cuiab\u00e1 em 2023. Segundo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10220,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10204"}],"collection":[{"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=10204"}],"version-history":[{"count":1,"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10204\/revisions"}],"predecessor-version":[{"id":10206,"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10204\/revisions\/10206"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/media\/10220"}],"wp:attachment":[{"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=10204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=10204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nazarenonews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=10204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}